{"id":76439,"date":"2024-04-22T10:04:55","date_gmt":"2024-04-22T13:04:55","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=76439"},"modified":"2024-04-22T15:20:56","modified_gmt":"2024-04-22T18:20:56","slug":"los-beneficiarios-del-bono-salteno-mas-de-70-anos-y-no-podran-tener-bienes-a-su-nombre","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2024\/04\/22\/los-beneficiarios-del-bono-salteno-mas-de-70-anos-y-no-podran-tener-bienes-a-su-nombre\/","title":{"rendered":"Los beneficiarios del bono salte\u00f1o: m\u00e1s de 70 a\u00f1os y no podr\u00e1n tener bienes a su nombre"},"content":{"rendered":"\n<p>Mediante el decreto 113\/24 se cre\u00f3 el Fondo Solidario de Apoyo Temporario para Jubilados salte\u00f1os que perciban haberes m\u00ednimos.<\/p>\n\n\n\n<p>A trav\u00e9s de la Resoluci\u00f3n 178 del ministerio de Econom\u00eda se reglament\u00f3 el alcance del beneficio y se determin\u00f3 el grupo etario favorecido por el Fondo Solidario.<\/p>\n\n\n\n<p>Estas son las condiciones requeridas:<\/p>\n\n\n\n<p>&#8211; Tener la edad de 70 (setenta) a\u00f1os o m\u00e1s,<\/p>\n\n\n\n<p>&#8211; Percibir el Haber Jubilatorio M\u00ednimo como \u00fanico ingreso, es decir que no registren a su favor pensiones o pensiones no contributivas,<\/p>\n\n\n\n<p>&#8211; No ser beneficiario de ning\u00fan ingreso relacionado a planes sociales nacionales, provinciales o municipales (AUH, Potenciar Trabajo, seguro de desempleo, etc.), ni de otra prestaci\u00f3n previsional,<\/p>\n\n\n\n<p>&#8211; Carecer de empleo en relaci\u00f3n de dependencia, sea independiente o presunto,<\/p>\n\n\n\n<p>&#8211; No percibir ingresos como permisionarios de estacionamiento medido<\/p>\n\n\n\n<p>&#8211; No tener ning\u00fan bien registrable a su nombre, sean automotores o inmuebles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mediante el decreto 113\/24 se cre\u00f3 el Fondo Solidario de Apoyo Temporario para Jubilados salte\u00f1os que perciban haberes m\u00ednimos. A trav\u00e9s de la Resoluci\u00f3n 178 del ministerio de Econom\u00eda se reglament\u00f3 el alcance del beneficio y se determin\u00f3 el grupo etario favorecido por el Fondo Solidario. Estas son las condiciones requeridas: &#8211; Tener la edad [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":75539,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[60],"tags":[],"class_list":{"0":"post-76439","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/76439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=76439"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/76439\/revisions"}],"predecessor-version":[{"id":76440,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/76439\/revisions\/76440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/75539"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=76439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=76439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=76439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}