{"id":83433,"date":"2024-09-09T18:50:41","date_gmt":"2024-09-09T21:50:41","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=83433"},"modified":"2024-09-09T18:50:42","modified_gmt":"2024-09-09T21:50:42","slug":"el-colegio-de-medicos-suspendio-la-matricula-de-65-profesionales-por-no-pagar-las-cuotas-societarias","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2024\/09\/09\/el-colegio-de-medicos-suspendio-la-matricula-de-65-profesionales-por-no-pagar-las-cuotas-societarias\/","title":{"rendered":"El Colegio de M\u00e9dicos suspendi\u00f3 la matr\u00edcula de 65 profesionales por no pagar las cuotas societarias"},"content":{"rendered":"\n<p>El Colegio de M\u00e9dicos de la provincia de Salta a trav\u00e9s de la Resoluci\u00f3n 124\/2024 suspendi\u00f3 la matr\u00edcula profesional otorgada 65 profesionales por la falta de pago de la cuota de los m\u00e9dicos colegiados.<\/p>\n\n\n\n<p>El informe fue elaborado por el Dpto. Contable del Colegio de M\u00e9dicos de Salta, luego de cumplidas todas las diligencias previas de notificaci\u00f3n de intimaci\u00f3n de pago, sin que los 65 profesionales hayan regularizado la situaci\u00f3n.<\/p>\n\n\n\n<p><strong>Los Medicos suspendidos<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"364\" height=\"537\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/09\/image-79.png\" alt=\"\" class=\"wp-image-83434\" style=\"width:1067px;height:auto\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/09\/image-79.png 364w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/09\/image-79-203x300.png 203w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/09\/image-79-285x420.png 285w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/09\/image-79-300x443.png 300w\" sizes=\"auto, (max-width: 364px) 100vw, 364px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"378\" height=\"340\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/09\/image-80.png\" alt=\"\" class=\"wp-image-83435\" style=\"width:1068px;height:auto\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/09\/image-80.png 378w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/09\/image-80-300x270.png 300w\" sizes=\"auto, (max-width: 378px) 100vw, 378px\" \/><\/figure>\n\n\n\n<p>La Resoluci\u00f3n N\u00b0 135\/12 establece que la falta de pago ante el requerimiento formal, es causal de Suspensi\u00f3n de la matr\u00edcula profesional, y que tal situaci\u00f3n implica la inhabilitaci\u00f3n correspondiente para ejercer la profesi\u00f3n en la provincia.<\/p>\n\n\n\n<p>La suspensi\u00f3n quedar\u00e1 sin efecto ante la cancelaci\u00f3n total de la deuda, incluyendo los gastos e intereses que se generen de tal tr\u00e1mite.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Colegio de M\u00e9dicos de la provincia de Salta a trav\u00e9s de la Resoluci\u00f3n 124\/2024 suspendi\u00f3 la matr\u00edcula profesional otorgada 65 profesionales por la falta de pago de la cuota de los m\u00e9dicos colegiados. El informe fue elaborado por el Dpto. Contable del Colegio de M\u00e9dicos de Salta, luego de cumplidas todas las diligencias previas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21780,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[73],"tags":[],"class_list":{"0":"post-83433","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-general"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/83433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=83433"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/83433\/revisions"}],"predecessor-version":[{"id":83436,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/83433\/revisions\/83436"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/21780"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=83433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=83433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=83433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}