{"id":92278,"date":"2025-03-06T20:42:57","date_gmt":"2025-03-06T23:42:57","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=92278"},"modified":"2025-03-06T20:42:58","modified_gmt":"2025-03-06T23:42:58","slug":"fue-a-bailar-se-quedo-a-dormir-en-la-casa-de-un-amigo-en-el-huaico-y-la-violo","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2025\/03\/06\/fue-a-bailar-se-quedo-a-dormir-en-la-casa-de-un-amigo-en-el-huaico-y-la-violo\/","title":{"rendered":"Fue a bailar se qued\u00f3 a dormir en la casa de un amigo en El Huaico y la viol\u00f3"},"content":{"rendered":"\n<p>En noviembre de 2023, una joven concurri\u00f3 a una fiesta en barrio El Huaico II junto a su novio y a una amiga. En el lugar consumieron bebidas alcoh\u00f3licas y se quedaron conversando hasta las 7. Cuando se dispon\u00edan a retirarse, ella tuvo una discusi\u00f3n con su pareja y decidi\u00f3 irse con un amigo, a quien le ten\u00eda mucha confianza. \u00c9l viv\u00eda en otro sector de El Huaico. Ella opt\u00f3 por dormir all\u00ed unas horas antes de volver a su casa.<\/p>\n\n\n\n<p>El joven (21) le prest\u00f3 ropa y ambos se acostaron en una misma cama. La denunciante le dio la espalda. Repentinamente \u00e9l comenz\u00f3 a tocarla en sus partes \u00edntimas. Ella le pidi\u00f3 por favor que la dejara, pero el sujeto la tom\u00f3 con fuerza y la accedi\u00f3 carnalmente sin su consentimiento.<\/p>\n\n\n\n<p>Ella se levant\u00f3 y quiso irse, pero \u00e9l se interpuso evitando que pudiera abrir la puerta. Le dijo: \u201cAhora que est\u00e1s aqu\u00ed ya no te voy a dejar ir, te voy a seguir molestando\u201d. Sigui\u00f3 toc\u00e1ndola mientras ella intentaba zafarse. Desisti\u00f3 cuando a ella comenz\u00f3 a sonarle el celular y le advirti\u00f3 que seguramente la estaban buscando.<\/p>\n\n\n\n<p>El agresor fue condenado a seis a\u00f1os de prisi\u00f3n por abuso sexual con acceso carnal. La audiencia de debate se llev\u00f3 a cabo en la Sala VII del Tribunal de Juicio, presidida por el juez Francisco Mascarello.<\/p>\n\n\n\n<p>Se orden\u00f3 el traslado del sujeto a la Unidad Carcelaria 1. Tambi\u00e9n que se le realice examen gen\u00e9tico (ADN) para su incorporaci\u00f3n en los bancos de datos correspondientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En noviembre de 2023, una joven concurri\u00f3 a una fiesta en barrio El Huaico II junto a su novio y a una amiga. En el lugar consumieron bebidas alcoh\u00f3licas y se quedaron conversando hasta las 7. Cuando se dispon\u00edan a retirarse, ella tuvo una discusi\u00f3n con su pareja y decidi\u00f3 irse con un amigo, a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":32416,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[63],"tags":[],"class_list":{"0":"post-92278","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policiales"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/92278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=92278"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/92278\/revisions"}],"predecessor-version":[{"id":92279,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/92278\/revisions\/92279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/32416"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=92278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=92278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=92278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}