{"id":92292,"date":"2025-03-06T21:20:24","date_gmt":"2025-03-07T00:20:24","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=92292"},"modified":"2025-03-06T21:20:25","modified_gmt":"2025-03-07T00:20:25","slug":"ya-se-trabaja-en-la-repavimentacion-de-la-avenida-ex-combatientes-de-malvinas","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2025\/03\/06\/ya-se-trabaja-en-la-repavimentacion-de-la-avenida-ex-combatientes-de-malvinas\/","title":{"rendered":"Ya se trabaja en la repavimentaci\u00f3n de la avenida Ex Combatientes de Malvinas"},"content":{"rendered":"\n<p>Los trabajos comenzaron desde la rotonda de ingreso al barrio Santa Ana, que tambi\u00e9n conecta con Cerrillos, y continuar\u00e1n hasta la rotonda de Limache. Esta obra beneficiar\u00e1 a 33 barrios y a m\u00e1s de 70 mil vecinos.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"716\" height=\"392\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2025\/03\/image-26.png\" alt=\"\" class=\"wp-image-92294\" style=\"width:1053px;height:auto\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2025\/03\/image-26.png 716w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2025\/03\/image-26-300x164.png 300w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2025\/03\/image-26-696x381.png 696w\" sizes=\"auto, (max-width: 716px) 100vw, 716px\" \/><\/figure>\n\n\n\n<p>Se trabaja en m\u00e1s de 8 kil\u00f3metros, en los que se realizar\u00e1 repavimentaci\u00f3n, nuevos accesos, ensanchamiento de veredas, nuevas d\u00e1rsenas y tambi\u00e9n se mejorar\u00e1 la iluminaci\u00f3n de la zona y los espacios verdes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"718\" height=\"399\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2025\/03\/image-27.png\" alt=\"\" class=\"wp-image-92295\" style=\"width:1053px;height:auto\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2025\/03\/image-27.png 718w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2025\/03\/image-27-300x167.png 300w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2025\/03\/image-27-696x387.png 696w\" sizes=\"auto, (max-width: 718px) 100vw, 718px\" \/><\/figure>\n\n\n\n<p>La obra comenz\u00f3 en el sentido sur \u2013 norte por lo que el tr\u00e1nsito se encuentra restringido debido a la presencia de maquinarias y operarios que, en primera instancia, est\u00e1n llevando a cabo la remoci\u00f3n de la calzada da\u00f1ada.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"710\" height=\"397\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2025\/03\/image-28.png\" alt=\"\" class=\"wp-image-92296\" style=\"width:1053px;height:auto\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2025\/03\/image-28.png 710w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2025\/03\/image-28-300x168.png 300w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2025\/03\/image-28-696x389.png 696w\" sizes=\"auto, (max-width: 710px) 100vw, 710px\" \/><\/figure>\n\n\n\n<p>Es importante destacar que esta obra beneficiar\u00e1 a 33 barrios y a m\u00e1s de 70 mil vecinos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los trabajos comenzaron desde la rotonda de ingreso al barrio Santa Ana, que tambi\u00e9n conecta con Cerrillos, y continuar\u00e1n hasta la rotonda de Limache. Esta obra beneficiar\u00e1 a 33 barrios y a m\u00e1s de 70 mil vecinos.&nbsp; Se trabaja en m\u00e1s de 8 kil\u00f3metros, en los que se realizar\u00e1 repavimentaci\u00f3n, nuevos accesos, ensanchamiento de veredas, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":92293,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[73],"tags":[],"class_list":{"0":"post-92292","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-general"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/92292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=92292"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/92292\/revisions"}],"predecessor-version":[{"id":92297,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/92292\/revisions\/92297"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/92293"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=92292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=92292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=92292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}