{"id":94793,"date":"2025-05-06T10:24:44","date_gmt":"2025-05-06T13:24:44","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=94793"},"modified":"2025-05-06T10:24:45","modified_gmt":"2025-05-06T13:24:45","slug":"un-joven-herido-en-un-impresionante-accidente-en-mosconi","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2025\/05\/06\/un-joven-herido-en-un-impresionante-accidente-en-mosconi\/","title":{"rendered":"Un joven herido en un impresionante accidente en Mosconi"},"content":{"rendered":"\n<p>Un joven oriundo de General Mosconi e hijo del empresario y ex candidato a intendente de esa ciudad, Miguel Ojeda choc\u00f3 violentamente contra la parte trasera de un cami\u00f3n recolector de residuos que ingresaba a una empresa ubicada sobre la ruta 34.<\/p>\n\n\n\n<p>El accidente se produjo cerca de las 7 de la ma\u00f1ana cuando el joven menor de edad conduc\u00eda una camioneta Toyota Hilux a alta velocidad y se dirig\u00eda de Mosconi a Tartagal al colegio donde cursa sus estudios.<\/p>\n\n\n\n<p>Por causas que se tratan de establecer colision\u00f3 violentamente contra el cami\u00f3n recolector de residuos de Mosconi.<\/p>\n\n\n\n<p>La camioneta qued\u00f3 destruida y el joven result\u00f3 herido y trasladado al hospital de Tartagal, donde se recupera favorablemente al no tener heridas graves.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un joven oriundo de General Mosconi e hijo del empresario y ex candidato a intendente de esa ciudad, Miguel Ojeda choc\u00f3 violentamente contra la parte trasera de un cami\u00f3n recolector de residuos que ingresaba a una empresa ubicada sobre la ruta 34. El accidente se produjo cerca de las 7 de la ma\u00f1ana cuando el [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":94794,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[63],"tags":[],"class_list":{"0":"post-94793","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policiales"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/94793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=94793"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/94793\/revisions"}],"predecessor-version":[{"id":94795,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/94793\/revisions\/94795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/94794"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=94793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=94793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=94793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}