{"id":94801,"date":"2025-05-06T17:26:43","date_gmt":"2025-05-06T20:26:43","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=94801"},"modified":"2025-05-06T17:26:44","modified_gmt":"2025-05-06T20:26:44","slug":"en-aguas-blancas-hay-hasta-60-bolivianos-registrados-en-una-vivienda-para-votar","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2025\/05\/06\/en-aguas-blancas-hay-hasta-60-bolivianos-registrados-en-una-vivienda-para-votar\/","title":{"rendered":"En Aguas Blancas hay hasta 60 bolivianos registrados en una vivienda para votar"},"content":{"rendered":"\n<p>El interventor de Aguas Blancas, Adri\u00e1n Zigar\u00e1n al hablar sobre las elecciones del pr\u00f3ximo domingo confirm\u00f3 que en el pueblo hay hasta 60 bolivianos con doble nacionalidad registrados en una sola vivienda, y que cruzar\u00e1n la frontera para votar.<\/p>\n\n\n\n<p>Asimismo, en di\u00e1logo con Radio Norte confirm\u00f3 que falta poco para la inauguraci\u00f3n del alambrado en la frontera con Bolivia.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"584\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2022\/06\/zigaran-1024x584.jpg\" alt=\"\" class=\"wp-image-40418\" style=\"width:1055px;height:auto\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2022\/06\/zigaran-1024x584.jpg 1024w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2022\/06\/zigaran-300x171.jpg 300w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2022\/06\/zigaran-768x438.jpg 768w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2022\/06\/zigaran-696x397.jpg 696w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2022\/06\/zigaran-737x420.jpg 737w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2022\/06\/zigaran.jpg 1044w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Adri\u00e1n Zigar\u00e1n<\/figcaption><\/figure>\n\n\n\n<p>\u201cEl alambrado ya cuenta con todos los postes instalados, incluir\u00e1 dos puertas y un port\u00f3n. En aproximadamente diez d\u00edas la obra estar\u00e1 finalizada\u201d, inform\u00f3 Zigar\u00e1n, y explic\u00f3 que hubo demoras debido a las inclemencias clim\u00e1ticas.<\/p>\n\n\n\n<p>Tambi\u00e9n se refiri\u00f3 a las cr\u00edticas recibidas: \u201cSe han burlado por los 200 metros de alambrado, cuestionando c\u00f3mo eso podr\u00eda frenar el contrabando. Veremos el impacto una vez que se inaugure\u201d. Se\u00f1al\u00f3 que, a partir de ese momento, todas las personas que deseen cruzar la frontera deber\u00e1n hacerlo por el paso habilitado de Migraciones, lo que podr\u00eda generar cierto malestar inicial.<\/p>\n\n\n\n<p>Zigar\u00e1n mencion\u00f3 adem\u00e1s el impacto del Plan G\u00fcemes, que ha generado reacciones negativas en algunos sectores, aunque \u201cya se empiezan a ver los resultados\u201d. En relaci\u00f3n al paso clandestino por Finca Karina, indic\u00f3 que all\u00ed Gendarmer\u00eda cuenta con esc\u00e1neres para controlar el contrabando, lo cual tambi\u00e9n ha provocado molestias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El interventor de Aguas Blancas, Adri\u00e1n Zigar\u00e1n al hablar sobre las elecciones del pr\u00f3ximo domingo confirm\u00f3 que en el pueblo hay hasta 60 bolivianos con doble nacionalidad registrados en una sola vivienda, y que cruzar\u00e1n la frontera para votar. Asimismo, en di\u00e1logo con Radio Norte confirm\u00f3 que falta poco para la inauguraci\u00f3n del alambrado en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":31118,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[59],"tags":[],"class_list":{"0":"post-94801","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/94801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=94801"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/94801\/revisions"}],"predecessor-version":[{"id":94802,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/94801\/revisions\/94802"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/31118"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=94801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=94801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=94801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}